{"id":1081,"date":"2018-09-07T11:58:24","date_gmt":"2018-09-07T09:58:24","guid":{"rendered":"https:\/\/ccic.hr\/it\/?p=1081"},"modified":"2018-09-07T11:58:38","modified_gmt":"2018-09-07T09:58:38","slug":"iniziativa-dellagenzia-del-demanio-per-il-recupero-di-beni-immobili-dello-stato-e-di-altri-enti-pubblici","status":"publish","type":"post","link":"https:\/\/ccic.hr\/it\/iniziativa-dellagenzia-del-demanio-per-il-recupero-di-beni-immobili-dello-stato-e-di-altri-enti-pubblici\/","title":{"rendered":"INIZIATIVA DELL\u2019AGENZIA DEL DEMANIO PER IL RECUPERO DI BENI IMMOBILI DELLO STATO E DI ALTRI ENTI PUBBLICI"},"content":{"rendered":"<p><a href=\"https:\/\/ccic.hr\/it\/iniziativa-dellagenzia-del-demanio-per-il-recupero-di-beni-immobili-dello-stato-e-di-altri-enti-pubblici\/faro\/\" rel=\"attachment wp-att-1082\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-large wp-image-1082\" src=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/sites\/2\/2018\/09\/faro-1024x320.jpg\" alt=\"\" width=\"840\" height=\"263\" srcset=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/sites\/2\/2018\/09\/faro-1024x320.jpg 1024w, https:\/\/ccic.hr\/it\/wp-content\/uploads\/sites\/2\/2018\/09\/faro-300x94.jpg 300w, https:\/\/ccic.hr\/it\/wp-content\/uploads\/sites\/2\/2018\/09\/faro-768x240.jpg 768w, https:\/\/ccic.hr\/it\/wp-content\/uploads\/sites\/2\/2018\/09\/faro.jpg 1200w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a>Nell\u2019ambito dell\u2019iniziativa \u201cValore Paese-Dimore\u201d avviata nel 2013 dell\u2019Agenzia del Demanio, volta alla riqualificazione di immobili pubblici di pregio storico-artistico e paesaggistico, selezionati sull\u2019intero territorio italiano per essere riutilizzati per finalit\u00e0 turistico ricettive e culturali<\/p>\n<p style=\"text-align: center\"><strong>SI INFORMA CHE<\/strong><\/p>\n<p>\u00e8 stato pubblicato il IV bando per \u201cFari, Torri ed Edifici Costieri\u201d, scadenza 27\/11\/2018. Maggiori informazioni sul bando e sulle procedure di partecipazione sono disponibili rispettivamente nei siti (anche in versione inglese) <a href=\"http:\/\/www.agenziademanio.it\/opencms\/it\/progetti\/fari\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.agenziademanio.it\/opencms\/it\/progetti\/fari\/<\/a> e <a href=\"http:\/\/vademecum.publicrealestate.it\/en\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/vademecum.publicrealestate.it\/en<\/a> .<\/p>\n<p>Per richieste di chiarimenti \u00e8 disponibile una casella di posta elettronica dedicata, alla quale risponde &#8211; anche in lingua inglese &#8211; personale specializzato dell\u2019Agenzia del Demanio <a href=\"mailto:dg.progettiarete@agenziadeldemanio.it\">dg.progettiarete@agenziadeldemanio.it<\/a> .<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019ambito dell\u2019iniziativa \u201cValore Paese-Dimore\u201d avviata nel 2013 dell\u2019Agenzia del Demanio, volta alla riqualificazione di immobili pubblici di pregio storico-artistico e paesaggistico, selezionati sull\u2019intero territorio italiano per essere riutilizzati per finalit\u00e0 turistico ricettive e culturali SI INFORMA CHE \u00e8 stato pubblicato il IV bando per \u201cFari, Torri ed Edifici Costieri\u201d, scadenza 27\/11\/2018. Maggiori informazioni sul bando [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1081","post","type-post","status-publish","format-standard","hentry","category-notizie"],"_links":{"self":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/comments?post=1081"}],"version-history":[{"count":2,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1081\/revisions"}],"predecessor-version":[{"id":1084,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1081\/revisions\/1084"}],"wp:attachment":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/media?parent=1081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/categories?post=1081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/tags?post=1081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}