{"id":1123,"date":"2019-01-22T11:43:18","date_gmt":"2019-01-22T10:43:18","guid":{"rendered":"https:\/\/ccic.hr\/it\/?p=1123"},"modified":"2019-01-22T11:43:18","modified_gmt":"2019-01-22T10:43:18","slug":"incontro-con-il-ministro-delleconomia-imprenditorialita-e-artigianato","status":"publish","type":"post","link":"https:\/\/ccic.hr\/it\/incontro-con-il-ministro-delleconomia-imprenditorialita-e-artigianato\/","title":{"rendered":"Incontro con il Ministro dell&#8217;economia, Imprenditorialit\u00e0 e Artigianato"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-nsm-1-1386\" src=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/2019\/01\/sastanak-min.-Horvat-300x223.jpg\" alt=\"\" width=\"300\" height=\"223\" \/><\/p>\n<p>Marted\u00ec , il 22 gennaio 2019, i rappresentanti delle Camere di commercio internazionali in Croazia hanno incontrato il Ministro dell&#8217;Economia, Imprenditorialit\u00e0 e Artigianato, il Sig. Dark Horvat, il Segretario dello Stato, il Sig. Zdenko Luci\u0107 e l&#8217;Assistente del Segretario, Sig.ra Bo\u017eica Lapic.<br \/>\nL&#8217;argomento dell&#8217;incontro \u00e8 stato il risultato della ricerca condotta dalle 6 Camere di commercio internazionali nel 2018 che hanno redatto i suggerimenti e le proposte per misure volte a migliorare l&#8217;ambiente imprenditoriale e migliorare gli scambi commerciali tra la Croazia e i paesi d&#8217;origine.<\/p>\n<p>Ricordiamo che nell&#8217;iniziativa hanno partecipato oltre la Camera di commercio italo croata, anche Camera di commercio americana (AmCham) in Croazia, Ufficio per il commercio estero austriaco, Rete commerciale canadese-croata (CCBN), Camera di commercio e industria tedesco-croato e Camera di commercio dei paesi nordici, con oltre 1.200 aziende associate in Croazia che impiegano oltre 150.000 persone e rappresentano oltre il 50 per cento degli investimenti esteri in Croazia.<br \/>\nIl Ministro, cos\u00ec come i suoi colleghi del Ministero dell&#8217;Economia, hanno accolto l&#8217;iniziativa e chiesto un dialogo pi\u00f9 frequente tra il Ministero e le Camere per miglioramenti fornendo una visione diretta delle reali esigenze degli imprenditori stranieri. Il Ministro ha proposto incontri con le Camere ogni due mesi allo scopo di creare miglioramenti comuni e accelerare i processi.<\/p>\n<p>Ci e&#8217; stato presentato il programma del MINGO che nel 2019 ha tre obiettivi strategici:<br \/>\n1. Crescita della produzione industriale<br \/>\n2. Crescita delle esportazioni<br \/>\n3. Aumentare il numero di innovazioni e la crescita dei RIS<br \/>\nIl Ministero ha preparato una mappa delle societ\u00e0 che sono della maggiore propriet\u00e0 statale, per le quali saranno ricercati partner o investitori stranieri. Gi\u00e0 questo venerd\u00ec, ci sar\u00e0 un invito a manifestare l&#8217;interesse per la ristrutturazione dei cantieri navali di Pola e Fiume, e il Ministro ha annunciato un grande interesse da parte degli investitori italiani.<br \/>\nInoltre, sono state annunciate nuove quote di energia, che secondo le parole del Ministro, saranno aumentate di tre volte, e i primi bandi sono previsti gi\u00e0 nella prima met\u00e0 di quest&#8217;anno.<\/p>\n<p>l Segretario di Stato, sig. Luci\u0107 ha inoltre presentato nuove misure per i prestiti per PMI da HAMAG &#8211; BICRO con tassi di interesse eccezionalmente favorevoli, la continua digitalizzazione dell&#8217;amministrazione statale e un processo di valutazione degli investimenti pi\u00f9 rapido ed efficiente. Luci\u0107 ha anche invitato le Camere a cooperare e sostenere il lavoro del Ministero.<br \/>\nLe Camere accolgono con favore ogni iniziativa volta a migliorare l&#8217;attivit\u00e0 in Croazia e sono aperte al dialogo e alla cooperazione.<br \/>\nPer continuare a fare i miglioramenti e dare i suggerimenti, la prossima settimana le Camere incontreranno il Ministro dell&#8217;amministrazione, il signor Lovro Ku\u0161\u010devi\u0107.<\/p>\n<p><img decoding=\"async\" class=\"alignleft size-medium wp-image-nsm-1-1387\" src=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/2019\/01\/20190121_153213-003-300x107.jpg\" alt=\"\" width=\"300\" height=\"107\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-nsm-1-1388\" src=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/2019\/01\/20190121_153129-002-300x146.jpg\" alt=\"\" width=\"300\" height=\"146\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-nsm-1-1389\" src=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/2019\/01\/sastanak-min.-Horvat-1jpg-300x146.jpg\" alt=\"\" width=\"300\" height=\"146\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec , il 22 gennaio 2019, i rappresentanti delle Camere di commercio internazionali in Croazia hanno incontrato il Ministro dell&#8217;Economia, Imprenditorialit\u00e0 e Artigianato, il Sig. Dark Horvat, il Segretario dello Stato, il Sig. Zdenko Luci\u0107 e l&#8217;Assistente del Segretario, Sig.ra Bo\u017eica Lapic. L&#8217;argomento dell&#8217;incontro \u00e8 stato il risultato della ricerca condotta dalle 6 Camere di [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1123","post","type-post","status-publish","format-standard","hentry","category-notizie"],"_links":{"self":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/comments?post=1123"}],"version-history":[{"count":1,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1123\/revisions"}],"predecessor-version":[{"id":1124,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1123\/revisions\/1124"}],"wp:attachment":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/media?parent=1123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/categories?post=1123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/tags?post=1123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}