{"id":1139,"date":"2019-02-19T11:08:43","date_gmt":"2019-02-19T10:08:43","guid":{"rendered":"https:\/\/ccic.hr\/it\/?p=1139"},"modified":"2019-02-19T14:03:18","modified_gmt":"2019-02-19T13:03:18","slug":"business-networking-breakfast","status":"publish","type":"post","link":"https:\/\/ccic.hr\/it\/business-networking-breakfast\/","title":{"rendered":"Business Networking Breakfast"},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-nsm-1-8\" src=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/2016\/10\/cropped-logo-1-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/> \u00a0 <img decoding=\"async\" class=\"alignleft size-full wp-image-nsm-1-1412\" src=\"https:\/\/ccic.hr\/wp-content\/uploads\/2019\/02\/ccbn.png\" alt=\"\" width=\"134\" height=\"90\" \/><\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">Il giorno 18 febbraio presso l&#8217;hotel Sheraton a zagabria si \u00e8 tenuto il BNB<\/p>\n<p style=\"text-align: left\">con la Camera di commercio canadese.<\/p>\n<p>I soci dell&#8217;AIIC hanno avuto possibilit\u00e0 durante gli appuntamenti brevi in forma<\/p>\n<p>\u201cspeed meeting\u201d di presentare le proprie aziende ai colleghi, membri del CBN e viceversa.<\/p>\n<p>Le aziende che hanno partecipato sono:<\/p>\n<p>Majo Commerce<\/p>\n<p>Primaco\u0161ped<\/p>\n<p>Hrvatska Po\u0161tanska Banka<\/p>\n<p>Luveti<\/p>\n<p>Obzor putovanja<\/p>\n<p>Wolf Theiss<\/p>\n<p>Importanne hotel &amp; resort<\/p>\n<p>Sheraton hotel<\/p>\n<p>Dialogo<\/p>\n<p>Manpower<\/p>\n<p>Service srl<\/p>\n<p>Eko dobra pri\u010da<\/p>\n<p>Calligaris<\/p>\n<p>Pkf Tax Anti\u010di\u0107<\/p>\n<p>&nbsp;<\/p>\n<p>Si \u00e8 mostrato il grande interesse per le collaborazioni tra gli imprenditori e approfondimenti<\/p>\n<p>che abbiamo continuato durante la colazione.<\/p>\n<p>Siamo felici che le collaborazioni con le altre Camere internazionali si continuano e che<\/p>\n<p>si aprono sempre pi\u00f9 possibilit\u00e0 d&#8217;affari.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-nsm-1-1414\" src=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/2019\/02\/20190218_090747-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-nsm-1-1416\" src=\"https:\/\/ccic.hr\/it\/wp-content\/uploads\/2019\/02\/20190218_090754-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Il giorno 18 febbraio presso l&#8217;hotel Sheraton a zagabria si \u00e8 tenuto il BNB con la Camera di commercio canadese. I soci dell&#8217;AIIC hanno avuto possibilit\u00e0 durante gli appuntamenti brevi in forma \u201cspeed meeting\u201d di presentare le proprie aziende ai colleghi, membri del CBN e viceversa. Le aziende che hanno partecipato sono: Majo Commerce [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1139","post","type-post","status-publish","format-standard","hentry","category-eventi"],"_links":{"self":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/comments?post=1139"}],"version-history":[{"count":3,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1139\/revisions"}],"predecessor-version":[{"id":1142,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1139\/revisions\/1142"}],"wp:attachment":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/media?parent=1139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/categories?post=1139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/tags?post=1139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}