{"id":1809,"date":"2020-02-04T10:10:26","date_gmt":"2020-02-04T09:10:26","guid":{"rendered":"https:\/\/ccic.hr\/it\/?p=1809"},"modified":"2020-02-04T10:11:11","modified_gmt":"2020-02-04T09:11:11","slug":"cerimonia-di-apertura-di-rijeka-capitale-europea-della-cultura-2020","status":"publish","type":"post","link":"https:\/\/ccic.hr\/it\/cerimonia-di-apertura-di-rijeka-capitale-europea-della-cultura-2020\/","title":{"rendered":"Cerimonia di apertura di Rijeka &#8211; Capitale europea della cultura 2020"},"content":{"rendered":"\n<p>Sabato 1 febbraio 2020, Fiume ha celebrato ufficialmente\nuno dei momenti pi\u00f9 importanti della sua storia recente, la citt\u00e0 porta\nufficialmente il titolo di Capitale europea della cultura. La cerimonia di\napertura si \u00e8 svolta presso l&#8217;HNK Ivan pl. Zajc, mentre l&#8217;evento centrale &#8211;\nOpera industriale \u00e8 stata eseguita nel porto di Fiume.<\/p>\n\n\n\n<p>Fiume si \u00e8 presentata agli occhi dell&#8217;Europa come una\ncitt\u00e0 moderna e ha reso omaggio ai suoi abitanti e alla tradizione artistica. L&#8217;Opera\nindustriale dal vivo \u00e8 stata eseguita da pi\u00f9 di cento artisti con l&#8217;aiuto delle\nmatrici, e allo spettacolo ha partecipato anche il pubblico che era di circa\n20.000 persone. Suono, musica e rumore, con la combinazione di luce e oscurit\u00e0,\nsono stati il \u200b\u200bfulcro dell&#8217;attraente programma di apertura.<\/p>\n\n\n\n<p>Alla cerimonia di apertura al Teatro\nNazionale Croato Ivan pl. Zajc hanno partecipato numerosi ospiti importanti dall&#8217;Europa\ne dalla Croazia. Molti artisti famosi, orchestre, cori, ensemble, ecc. si sono\nesibiti nella parte musicale e scenica del programma.<\/p>\n\n\n\n<p>Il programma \u00e8 iniziato alle 7 del mattino al caff\u00e8 bar Skradin, da dove si \u00e8 partiti ad un tour anti-turistico con bus turistico di Fiume a due piani. Il programma Fiume, Passi e Tempo \u00e8 l&#8217;evento che attira maggiormente l&#8217;attenzione perch\u00e8 i visitatori vengono introdotti nei eventi importanti negli ultimi 116 anni della storia di Fiume, utilizzando una linea temporale di 232 metri impostata sul Korzo.<\/p>\n\n\n\n<p>Concerti, spettacoli e luoghi di danza sono stati tenuti in numerose altre localit\u00e0 della citt\u00e0. \u00c8 stato molto interessante nel mercato del pesce di Fiume perch\u00e9 \u00e8 stata tenuta una performance dallo studio vocale Fiume, che ha sorpreso i clienti. Per tutto il pomeriggio e la sera si sono tenuti vari concerti ed esibizioni di DJ.<\/p>\n\n\n\n<p>Con l&#8217;attraente spettacolo pirotecnico sopra le barche\nche circondano il mare, si \u00e8 conclusa la parte ufficiale dell&#8217;apertura, dopo di\nche i cittadini si sono dispersi nei club che erano aperti fino alle prime ore\ndel mattino. <strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 1 febbraio 2020, Fiume ha celebrato ufficialmente uno dei momenti pi\u00f9 importanti della sua storia recente, la citt\u00e0 porta ufficialmente il titolo di Capitale europea della cultura. La cerimonia di apertura si \u00e8 svolta presso l&#8217;HNK Ivan pl. Zajc, mentre l&#8217;evento centrale &#8211; Opera industriale \u00e8 stata eseguita nel porto di Fiume. Fiume si [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,9],"tags":[],"class_list":["post-1809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","category-in-evidenza"],"_links":{"self":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/comments?post=1809"}],"version-history":[{"count":1,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1809\/revisions"}],"predecessor-version":[{"id":1811,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/posts\/1809\/revisions\/1811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/media\/1810"}],"wp:attachment":[{"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/media?parent=1809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/categories?post=1809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccic.hr\/it\/wp-json\/wp\/v2\/tags?post=1809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}